{"id":3505,"date":"2016-03-25T11:53:10","date_gmt":"2016-03-25T18:53:10","guid":{"rendered":"https:\/\/daveworks.net\/web-design-development-tips\/?p=3505"},"modified":"2016-11-03T00:18:43","modified_gmt":"2016-11-03T07:18:43","slug":"advanced-google-searching-techniques","status":"publish","type":"post","link":"https:\/\/daveworks.net\/web-design-development-tips\/podcast\/advanced-google-searching-techniques\/","title":{"rendered":"Advanced Google Searching Techniques"},"content":{"rendered":"<div itemscope itemtype=\"http:\/\/schema.org\/AudioObject\"><meta itemprop=\"name\" content=\"Advanced Google Searching Techniques\" \/><meta itemprop=\"uploadDate\" content=\"2016-03-25T11:53:10-07:00\" \/><meta itemprop=\"encodingFormat\" content=\"audio\/mpeg\" \/><meta itemprop=\"description\" content=\"Podcast: Advanced Google Searching Techniques\r\n\r\n\r\n\r\nAdvanced Google Searching Techniques, by Dave Naves. Previously recorded on KAHI Radio 950AM, March 25th, 2016\r\n\r\n\r\nLearn more about Advanced Google Searching Techniques at Lynda. \r\n\r\n\" \/><meta itemprop=\"contentUrl\" content=\"https:\/\/daveworks.net\/podcast\/dave_naves_kahi_radio_advanced_google-search_march_25_2016.mp3\" \/><div class=\"powerpress_player\" id=\"powerpress_player_8618\"><audio class=\"wp-audio-shortcode\" id=\"audio-3505-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/daveworks.net\/podcast\/dave_naves_kahi_radio_advanced_google-search_march_25_2016.mp3?_=1\" \/><a href=\"https:\/\/daveworks.net\/podcast\/dave_naves_kahi_radio_advanced_google-search_march_25_2016.mp3\">https:\/\/daveworks.net\/podcast\/dave_naves_kahi_radio_advanced_google-search_march_25_2016.mp3<\/a><\/audio><\/div><\/div><p class=\"powerpress_links powerpress_links_mp3\" style=\"margin-bottom: 1px !important;\">Podcast: <a href=\"https:\/\/daveworks.net\/podcast\/dave_naves_kahi_radio_advanced_google-search_march_25_2016.mp3\" class=\"powerpress_link_pinw\" target=\"_blank\" title=\"Play in new window\" onclick=\"return powerpress_pinw('https:\/\/daveworks.net\/web-design-development-tips\/?powerpress_pinw=3505-podcast');\" rel=\"nofollow\">Play in new window<\/a> | <a href=\"https:\/\/daveworks.net\/podcast\/dave_naves_kahi_radio_advanced_google-search_march_25_2016.mp3\" class=\"powerpress_link_d\" title=\"Download\" rel=\"nofollow\" download=\"dave_naves_kahi_radio_advanced_google-search_march_25_2016.mp3\">Download<\/a> | <a href=\"#\" class=\"powerpress_link_e\" title=\"Embed\" onclick=\"return powerpress_show_embed('3505-podcast');\" rel=\"nofollow\">Embed<\/a><\/p><p class=\"powerpress_embed_box\" id=\"powerpress_embed_3505-podcast\" style=\"display: none;\"><input id=\"powerpress_embed_3505-podcast_t\" type=\"text\" value=\"&lt;iframe width=&quot;320&quot; height=&quot;30&quot; src=&quot;https:\/\/daveworks.net\/web-design-development-tips\/?powerpress_embed=3505-podcast&amp;amp;powerpress_player=mediaelement-audio&quot; title=&quot;Blubrry Podcast Player&quot; frameborder=&quot;0&quot; scrolling=&quot;no&quot;&gt;&lt;\/iframe&gt;\" onclick=\"javascript: this.select();\" onfocus=\"javascript: this.select();\" style=\"width: 70%;\" readOnly><\/p><p class=\"powerpress_links powerpress_subscribe_links\">Subscribe: <a href=\"https:\/\/itunes.apple.com\/us\/podcast\/web-in-plain-english-by-dave\/id1021502818?mt=2&amp;ls=1#episodeGuid=https%3A%2F%2Fdaveworks.net%2Fweb-design-development-tips%2F%3Fp%3D3505\" class=\"powerpress_link_subscribe powerpress_link_subscribe_itunes\" target=\"_blank\" title=\"Subscribe on Apple Podcasts\" rel=\"nofollow\">Apple Podcasts<\/a> | <a href=\"https:\/\/subscribebyemail.com\/daveworks.net\/web-design-development-tips\/feed\/podcast\/\" class=\"powerpress_link_subscribe powerpress_link_subscribe_email\" target=\"_blank\" title=\"Subscribe by Email\" rel=\"nofollow\">Email<\/a> | <a href=\"https:\/\/daveworks.net\/web-design-development-tips\/feed\/podcast\/\" class=\"powerpress_link_subscribe powerpress_link_subscribe_rss\" target=\"_blank\" title=\"Subscribe via RSS\" rel=\"nofollow\">RSS<\/a><\/p><h2>Podcast: Advanced Google Searching Techniques<\/h2>\n<div id=\"attachment_3500\" style=\"width: 360px\" class=\"wp-caption alignright\"><img decoding=\"async\" aria-describedby=\"caption-attachment-3500\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-orig-src=\"https:\/\/daveworks.net\/web-design-development-tips\/wp-content\/uploads\/google-logo-500x208.jpg\" alt=\"Advanced Google Searching Techniques in Plain English\" width=\"350\" class=\"lazyload size-medium wp-image-3500\" \/><p id=\"caption-attachment-3500\" class=\"wp-caption-text\">Advanced Google Searching Techniques<\/p><\/div>\n<p>Advanced Google Searching Techniques, by Dave Naves. Previously recorded on KAHI Radio 950AM, March 25th, 2016<\/p>\n<p><strong><a href=\"https:\/\/www.lynda.com\/Educational-Technology-tutorials\/Use-keywords-filters-Google-Search\/373783\/456242-4.html?utm_medium=ldc-partner&#038;utm_source=SSPRC&#038;utm_content=524&#038;utm_campaign=CD3677&#038;bid=524&#038;aid=CD3677\" target=\"_blank\" rel=\"nofollow\">Learn more about Advanced Google Searching Techniques at Lynda.<\/a> <\/strong><\/p>\n<p><iframe data-privacy-type=\"youtube\" src=\"\" class=\"fusion-hidden lazyload\" width=\"640\" height=\"480\" data-privacy-src=\"https:\/\/www.youtube.com\/embed\/asBxv5bzRQo\" data-orig-src=\"https:\/\/www.youtube.com\/embed\/asBxv5bzRQo\" frameborder=\"0\" allowfullscreen><\/iframe><div class=\"fusion-privacy-placeholder\" style=\"width:640px; height:480px;\" data-privacy-type=\"youtube\"><div class=\"fusion-privacy-placeholder-content\"><div class=\"fusion-privacy-label\">For privacy reasons YouTube needs your permission to be loaded.<\/div><button data-privacy-type=\"youtube\" class=\"fusion-button button-default fusion-button-default-size button fusion-privacy-consent\">I Accept<\/button><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<div itemscope itemtype=\"http:\/\/schema.org\/AudioObject\"><meta itemprop=\"name\" content=\"Advanced Google Searching Techniques\" \/><meta itemprop=\"uploadDate\" content=\"2016-03-25T11:53:10-07:00\" \/><meta itemprop=\"encodingFormat\" content=\"audio\/mpeg\" \/><meta itemprop=\"description\" content=\"Podcast: Advanced Google Searching Techniques\r\n\r\n\r\n\r\nAdvanced Google Searching Techniques, by Dave Naves. Previously recorded on KAHI Radio 950AM, March 25th, 2016\r\n\r\n\r\nLearn more about Advanced Google Searching Techniques at Lynda. \r\n\r\n\" \/><meta itemprop=\"contentUrl\" content=\"https:\/\/daveworks.net\/podcast\/dave_naves_kahi_radio_advanced_google-search_march_25_2016.mp3\" \/><div class=\"powerpress_player\" id=\"powerpress_player_8619\"><audio class=\"wp-audio-shortcode\" id=\"audio-3505-2\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/daveworks.net\/podcast\/dave_naves_kahi_radio_advanced_google-search_march_25_2016.mp3?_=2\" \/><a href=\"https:\/\/daveworks.net\/podcast\/dave_naves_kahi_radio_advanced_google-search_march_25_2016.mp3\">https:\/\/daveworks.net\/podcast\/dave_naves_kahi_radio_advanced_google-search_march_25_2016.mp3<\/a><\/audio><\/div><\/div><p class=\"powerpress_links powerpress_links_mp3\" style=\"margin-bottom: 1px !important;\">Podcast: <a href=\"https:\/\/daveworks.net\/podcast\/dave_naves_kahi_radio_advanced_google-search_march_25_2016.mp3\" class=\"powerpress_link_pinw\" target=\"_blank\" title=\"Play in new window\" onclick=\"return powerpress_pinw('https:\/\/daveworks.net\/web-design-development-tips\/?powerpress_pinw=3505-podcast');\" rel=\"nofollow\">Play in new window<\/a> | <a href=\"https:\/\/daveworks.net\/podcast\/dave_naves_kahi_radio_advanced_google-search_march_25_2016.mp3\" class=\"powerpress_link_d\" title=\"Download\" rel=\"nofollow\" download=\"dave_naves_kahi_radio_advanced_google-search_march_25_2016.mp3\">Download<\/a> | <a href=\"#\" class=\"powerpress_link_e\" title=\"Embed\" onclick=\"return powerpress_show_embed('3505-podcast');\" rel=\"nofollow\">Embed<\/a><\/p><p class=\"powerpress_embed_box\" id=\"powerpress_embed_3505-podcast\" style=\"display: none;\"><input id=\"powerpress_embed_3505-podcast_t\" type=\"text\" value=\"&lt;iframe width=&quot;320&quot; height=&quot;30&quot; src=&quot;https:\/\/daveworks.net\/web-design-development-tips\/?powerpress_embed=3505-podcast&amp;amp;powerpress_player=mediaelement-audio&quot; title=&quot;Blubrry Podcast Player&quot; frameborder=&quot;0&quot; scrolling=&quot;no&quot;&gt;&lt;\/iframe&gt;\" onclick=\"javascript: this.select();\" onfocus=\"javascript: this.select();\" style=\"width: 70%;\" readOnly><\/p><p class=\"powerpress_links powerpress_subscribe_links\">Subscribe: <a href=\"https:\/\/itunes.apple.com\/us\/podcast\/web-in-plain-english-by-dave\/id1021502818?mt=2&amp;ls=1#episodeGuid=https%3A%2F%2Fdaveworks.net%2Fweb-design-development-tips%2F%3Fp%3D3505\" class=\"powerpress_link_subscribe powerpress_link_subscribe_itunes\" target=\"_blank\" title=\"Subscribe on Apple Podcasts\" rel=\"nofollow\">Apple Podcasts<\/a> | <a href=\"https:\/\/subscribebyemail.com\/daveworks.net\/web-design-development-tips\/feed\/podcast\/\" class=\"powerpress_link_subscribe powerpress_link_subscribe_email\" target=\"_blank\" title=\"Subscribe by Email\" rel=\"nofollow\">Email<\/a> | <a href=\"https:\/\/daveworks.net\/web-design-development-tips\/feed\/podcast\/\" class=\"powerpress_link_subscribe powerpress_link_subscribe_rss\" target=\"_blank\" title=\"Subscribe via RSS\" rel=\"nofollow\">RSS<\/a><\/p><p>Podcast: Advanced Google Searching Techniques Advanced Google Searching Techniques, by&hellip; <a class=\"continue\" href=\"https:\/\/daveworks.net\/web-design-development-tips\/podcast\/advanced-google-searching-techniques\/\">Continue Reading<span> Advanced Google Searching Techniques<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":1297,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[568],"tags":[609,610,611],"class_list":["post-3505","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-podcast","tag-advanced-google-searching-techniques","tag-how-to-use-google","tag-how-to-use-google-search"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Advanced Google Searching Techniques, by Dave Naves. Previously recorded on KAHI Radio 950AM, March 25th, 2016\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"David Naves\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/daveworks.net\/web-design-development-tips\/podcast\/advanced-google-searching-techniques\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Daveworks Web Development\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Advanced Google Searching Techniques\" \/>\n\t\t<meta property=\"og:description\" content=\"Advanced Google Searching Techniques, by Dave Naves. Previously recorded on KAHI Radio 950AM, March 25th, 2016\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/daveworks.net\/web-design-development-tips\/podcast\/advanced-google-searching-techniques\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/daveworks.net\/web-design-development-tips\/wp-content\/uploads\/daveworks-pc-background-scaled.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/daveworks.net\/web-design-development-tips\/wp-content\/uploads\/daveworks-pc-background-scaled.jpg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-03-25T18:53:10+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-11-03T07:18:43+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/daveworks\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@dhnaves\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Advanced Google Searching Techniques\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Advanced Google Searching Techniques, by Dave Naves. Previously recorded on KAHI Radio 950AM, March 25th, 2016\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/daveworks.net\/web-design-development-tips\/wp-content\/uploads\/daveworks-pc-background-scaled.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/daveworks.net\\\/web-design-development-tips\\\/podcast\\\/advanced-google-searching-techniques\\\/#article\",\"name\":\"Advanced Google Searching Techniques\",\"headline\":\"Advanced Google Searching Techniques\",\"author\":{\"@id\":\"https:\\\/\\\/daveworks.net\\\/web-design-development-tips\\\/author\\\/dave-2-2-2-2\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/daveworks.net\\\/web-design-development-tips\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/daveworks.net\\\/web-design-development-tips\\\/wp-content\\\/uploads\\\/google-logo.jpg\",\"width\":3600,\"height\":1500,\"caption\":\"Google Advanced Search\"},\"datePublished\":\"2016-03-25T11:53:10-07:00\",\"dateModified\":\"2016-11-03T00:18:43-07:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/daveworks.net\\\/web-design-development-tips\\\/podcast\\\/advanced-google-searching-techniques\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/daveworks.net\\\/web-design-development-tips\\\/podcast\\\/advanced-google-searching-techniques\\\/#webpage\"},\"articleSection\":\"Podcast, Advanced Google Searching Techniques, How to use Google, How to use Google Search\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/daveworks.net\\\/web-design-development-tips\\\/podcast\\\/advanced-google-searching-techniques\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/daveworks.net\\\/web-design-development-tips#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/daveworks.net\\\/web-design-development-tips\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/daveworks.net\\\/web-design-development-tips\\\/category\\\/podcast\\\/#listItem\",\"name\":\"Podcast\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/daveworks.net\\\/web-design-development-tips\\\/category\\\/podcast\\\/#listItem\",\"position\":2,\"name\":\"Podcast\",\"item\":\"https:\\\/\\\/daveworks.net\\\/web-design-development-tips\\\/category\\\/podcast\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/daveworks.net\\\/web-design-development-tips\\\/podcast\\\/advanced-google-searching-techniques\\\/#listItem\",\"name\":\"Advanced Google Searching Techniques\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/daveworks.net\\\/web-design-development-tips#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/daveworks.net\\\/web-design-development-tips\\\/podcast\\\/advanced-google-searching-techniques\\\/#listItem\",\"position\":3,\"name\":\"Advanced Google Searching Techniques\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/daveworks.net\\\/web-design-development-tips\\\/category\\\/podcast\\\/#listItem\",\"name\":\"Podcast\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/daveworks.net\\\/web-design-development-tips\\\/#organization\",\"name\":\"Daveworks Web Development\",\"description\":\"Daveworks Web Development is a premium Northern California agency specializing in custom WordPress engineering, high-performance WooCommerce solutions, advanced Local SEO, and AI Search Optimization (GEO). Founded by digital expert David Naves, Daveworks applies a signature 5-layer development methodology\\u2014design, development, optimization, socialization, and training\\u2014to build high-ROI digital footprints for small-to-midsize businesses.\",\"url\":\"https:\\\/\\\/daveworks.net\\\/web-design-development-tips\\\/\",\"email\":\"dave@daveworks.net\",\"telephone\":\"+15308309088\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/daveworks.net\\\/web-design-development-tips\\\/wp-content\\\/uploads\\\/daveworks-pc-background-scaled.jpg\",\"@id\":\"https:\\\/\\\/daveworks.net\\\/web-design-development-tips\\\/podcast\\\/advanced-google-searching-techniques\\\/#organizationLogo\",\"width\":2560,\"height\":1017,\"caption\":\"Daveworks Web Development Logo | Web Design in Northern CA\"},\"image\":{\"@id\":\"https:\\\/\\\/daveworks.net\\\/web-design-development-tips\\\/podcast\\\/advanced-google-searching-techniques\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/daveworksweb\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCmZ9eZNADIaRUQaXG76fiCw\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/daveworks-web-development\"],\"address\":{\"@id\":\"https:\\\/\\\/daveworks.net\\\/web-design-development-tips\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"2945 Bell Road 320\",\"postalCode\":\"95603\",\"addressLocality\":\"Auburn\",\"addressRegion\":\"CA\",\"addressCountry\":\"US\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/daveworks.net\\\/web-design-development-tips\\\/author\\\/dave-2-2-2-2\\\/#author\",\"url\":\"https:\\\/\\\/daveworks.net\\\/web-design-development-tips\\\/author\\\/dave-2-2-2-2\\\/\",\"name\":\"David Naves\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/daveworks.net\\\/web-design-development-tips\\\/podcast\\\/advanced-google-searching-techniques\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/91f5fdb120990253993eddc2476466f038c51c5963d1d478080f12c87f76c8cf?s=96&d=identicon&r=g\",\"width\":96,\"height\":96,\"caption\":\"David Naves\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/daveworks.net\\\/web-design-development-tips\\\/podcast\\\/advanced-google-searching-techniques\\\/#webpage\",\"url\":\"https:\\\/\\\/daveworks.net\\\/web-design-development-tips\\\/podcast\\\/advanced-google-searching-techniques\\\/\",\"name\":\"Advanced Google Searching Techniques\",\"description\":\"Advanced Google Searching Techniques, by Dave Naves. Previously recorded on KAHI Radio 950AM, March 25th, 2016\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/daveworks.net\\\/web-design-development-tips\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/daveworks.net\\\/web-design-development-tips\\\/podcast\\\/advanced-google-searching-techniques\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/daveworks.net\\\/web-design-development-tips\\\/author\\\/dave-2-2-2-2\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/daveworks.net\\\/web-design-development-tips\\\/author\\\/dave-2-2-2-2\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/daveworks.net\\\/web-design-development-tips\\\/wp-content\\\/uploads\\\/google-logo.jpg\",\"@id\":\"https:\\\/\\\/daveworks.net\\\/web-design-development-tips\\\/podcast\\\/advanced-google-searching-techniques\\\/#mainImage\",\"width\":3600,\"height\":1500,\"caption\":\"Google Advanced Search\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/daveworks.net\\\/web-design-development-tips\\\/podcast\\\/advanced-google-searching-techniques\\\/#mainImage\"},\"datePublished\":\"2016-03-25T11:53:10-07:00\",\"dateModified\":\"2016-11-03T00:18:43-07:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/daveworks.net\\\/web-design-development-tips\\\/#website\",\"url\":\"https:\\\/\\\/daveworks.net\\\/web-design-development-tips\\\/\",\"name\":\"Daveworks Web Development\",\"description\":\"Small Business Specialists: Web Development | SEO | eCommerce | Social Networking\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/daveworks.net\\\/web-design-development-tips\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Advanced Google Searching Techniques<\/title>\n\n","aioseo_head_json":{"title":"Advanced Google Searching Techniques","description":"Advanced Google Searching Techniques, by Dave Naves. Previously recorded on KAHI Radio 950AM, March 25th, 2016","canonical_url":"https:\/\/daveworks.net\/web-design-development-tips\/podcast\/advanced-google-searching-techniques\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/daveworks.net\/web-design-development-tips\/podcast\/advanced-google-searching-techniques\/#article","name":"Advanced Google Searching Techniques","headline":"Advanced Google Searching Techniques","author":{"@id":"https:\/\/daveworks.net\/web-design-development-tips\/author\/dave-2-2-2-2\/#author"},"publisher":{"@id":"https:\/\/daveworks.net\/web-design-development-tips\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/daveworks.net\/web-design-development-tips\/wp-content\/uploads\/google-logo.jpg","width":3600,"height":1500,"caption":"Google Advanced Search"},"datePublished":"2016-03-25T11:53:10-07:00","dateModified":"2016-11-03T00:18:43-07:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/daveworks.net\/web-design-development-tips\/podcast\/advanced-google-searching-techniques\/#webpage"},"isPartOf":{"@id":"https:\/\/daveworks.net\/web-design-development-tips\/podcast\/advanced-google-searching-techniques\/#webpage"},"articleSection":"Podcast, Advanced Google Searching Techniques, How to use Google, How to use Google Search"},{"@type":"BreadcrumbList","@id":"https:\/\/daveworks.net\/web-design-development-tips\/podcast\/advanced-google-searching-techniques\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/daveworks.net\/web-design-development-tips#listItem","position":1,"name":"Home","item":"https:\/\/daveworks.net\/web-design-development-tips","nextItem":{"@type":"ListItem","@id":"https:\/\/daveworks.net\/web-design-development-tips\/category\/podcast\/#listItem","name":"Podcast"}},{"@type":"ListItem","@id":"https:\/\/daveworks.net\/web-design-development-tips\/category\/podcast\/#listItem","position":2,"name":"Podcast","item":"https:\/\/daveworks.net\/web-design-development-tips\/category\/podcast\/","nextItem":{"@type":"ListItem","@id":"https:\/\/daveworks.net\/web-design-development-tips\/podcast\/advanced-google-searching-techniques\/#listItem","name":"Advanced Google Searching Techniques"},"previousItem":{"@type":"ListItem","@id":"https:\/\/daveworks.net\/web-design-development-tips#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/daveworks.net\/web-design-development-tips\/podcast\/advanced-google-searching-techniques\/#listItem","position":3,"name":"Advanced Google Searching Techniques","previousItem":{"@type":"ListItem","@id":"https:\/\/daveworks.net\/web-design-development-tips\/category\/podcast\/#listItem","name":"Podcast"}}]},{"@type":"Organization","@id":"https:\/\/daveworks.net\/web-design-development-tips\/#organization","name":"Daveworks Web Development","description":"Daveworks Web Development is a premium Northern California agency specializing in custom WordPress engineering, high-performance WooCommerce solutions, advanced Local SEO, and AI Search Optimization (GEO). Founded by digital expert David Naves, Daveworks applies a signature 5-layer development methodology\u2014design, development, optimization, socialization, and training\u2014to build high-ROI digital footprints for small-to-midsize businesses.","url":"https:\/\/daveworks.net\/web-design-development-tips\/","email":"dave@daveworks.net","telephone":"+15308309088","logo":{"@type":"ImageObject","url":"https:\/\/daveworks.net\/web-design-development-tips\/wp-content\/uploads\/daveworks-pc-background-scaled.jpg","@id":"https:\/\/daveworks.net\/web-design-development-tips\/podcast\/advanced-google-searching-techniques\/#organizationLogo","width":2560,"height":1017,"caption":"Daveworks Web Development Logo | Web Design in Northern CA"},"image":{"@id":"https:\/\/daveworks.net\/web-design-development-tips\/podcast\/advanced-google-searching-techniques\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/daveworksweb","https:\/\/www.youtube.com\/channel\/UCmZ9eZNADIaRUQaXG76fiCw","https:\/\/www.linkedin.com\/company\/daveworks-web-development"],"address":{"@id":"https:\/\/daveworks.net\/web-design-development-tips\/#postaladdress","@type":"PostalAddress","streetAddress":"2945 Bell Road 320","postalCode":"95603","addressLocality":"Auburn","addressRegion":"CA","addressCountry":"US"}},{"@type":"Person","@id":"https:\/\/daveworks.net\/web-design-development-tips\/author\/dave-2-2-2-2\/#author","url":"https:\/\/daveworks.net\/web-design-development-tips\/author\/dave-2-2-2-2\/","name":"David Naves","image":{"@type":"ImageObject","@id":"https:\/\/daveworks.net\/web-design-development-tips\/podcast\/advanced-google-searching-techniques\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/91f5fdb120990253993eddc2476466f038c51c5963d1d478080f12c87f76c8cf?s=96&d=identicon&r=g","width":96,"height":96,"caption":"David Naves"}},{"@type":"WebPage","@id":"https:\/\/daveworks.net\/web-design-development-tips\/podcast\/advanced-google-searching-techniques\/#webpage","url":"https:\/\/daveworks.net\/web-design-development-tips\/podcast\/advanced-google-searching-techniques\/","name":"Advanced Google Searching Techniques","description":"Advanced Google Searching Techniques, by Dave Naves. Previously recorded on KAHI Radio 950AM, March 25th, 2016","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/daveworks.net\/web-design-development-tips\/#website"},"breadcrumb":{"@id":"https:\/\/daveworks.net\/web-design-development-tips\/podcast\/advanced-google-searching-techniques\/#breadcrumblist"},"author":{"@id":"https:\/\/daveworks.net\/web-design-development-tips\/author\/dave-2-2-2-2\/#author"},"creator":{"@id":"https:\/\/daveworks.net\/web-design-development-tips\/author\/dave-2-2-2-2\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/daveworks.net\/web-design-development-tips\/wp-content\/uploads\/google-logo.jpg","@id":"https:\/\/daveworks.net\/web-design-development-tips\/podcast\/advanced-google-searching-techniques\/#mainImage","width":3600,"height":1500,"caption":"Google Advanced Search"},"primaryImageOfPage":{"@id":"https:\/\/daveworks.net\/web-design-development-tips\/podcast\/advanced-google-searching-techniques\/#mainImage"},"datePublished":"2016-03-25T11:53:10-07:00","dateModified":"2016-11-03T00:18:43-07:00"},{"@type":"WebSite","@id":"https:\/\/daveworks.net\/web-design-development-tips\/#website","url":"https:\/\/daveworks.net\/web-design-development-tips\/","name":"Daveworks Web Development","description":"Small Business Specialists: Web Development | SEO | eCommerce | Social Networking","inLanguage":"en-US","publisher":{"@id":"https:\/\/daveworks.net\/web-design-development-tips\/#organization"}}]},"og:locale":"en_US","og:site_name":"Daveworks Web Development","og:type":"article","og:title":"Advanced Google Searching Techniques","og:description":"Advanced Google Searching Techniques, by Dave Naves. Previously recorded on KAHI Radio 950AM, March 25th, 2016","og:url":"https:\/\/daveworks.net\/web-design-development-tips\/podcast\/advanced-google-searching-techniques\/","og:image":"https:\/\/daveworks.net\/web-design-development-tips\/wp-content\/uploads\/daveworks-pc-background-scaled.jpg","og:image:secure_url":"https:\/\/daveworks.net\/web-design-development-tips\/wp-content\/uploads\/daveworks-pc-background-scaled.jpg","article:published_time":"2016-03-25T18:53:10+00:00","article:modified_time":"2016-11-03T07:18:43+00:00","article:publisher":"https:\/\/www.facebook.com\/daveworks","twitter:card":"summary","twitter:site":"@dhnaves","twitter:title":"Advanced Google Searching Techniques","twitter:description":"Advanced Google Searching Techniques, by Dave Naves. Previously recorded on KAHI Radio 950AM, March 25th, 2016","twitter:image":"https:\/\/daveworks.net\/web-design-development-tips\/wp-content\/uploads\/daveworks-pc-background-scaled.jpg"},"aioseo_meta_data":{"post_id":"3505","title":"Advanced Google Searching Techniques","description":"Advanced Google Searching Techniques, by Dave Naves. Previously recorded on KAHI Radio 950AM, March 25th, 2016","keywords":[{"label":"Advanced Google Searching Techniques","value":"Advanced Google Searching Techniques"},{"label":"Advanced Google Searching Techniques","value":"Advanced Google Searching Techniques"},{"label":"How to use Google","value":"How to use Google"},{"label":"How to use Google Search","value":"How to use Google Search"}],"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-07-12 18:01:47","updated":"2026-05-22 17:57:00","seo_analyzer_scan_date":"2026-05-22 17:43:30","reviewed_by":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/daveworks.net\/web-design-development-tips\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/daveworks.net\/web-design-development-tips\/category\/podcast\/\" title=\"Podcast\">Podcast<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tAdvanced Google Searching Techniques\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/daveworks.net\/web-design-development-tips"},{"label":"Podcast","link":"https:\/\/daveworks.net\/web-design-development-tips\/category\/podcast\/"},{"label":"Advanced Google Searching Techniques","link":"https:\/\/daveworks.net\/web-design-development-tips\/podcast\/advanced-google-searching-techniques\/"}],"_links":{"self":[{"href":"https:\/\/daveworks.net\/web-design-development-tips\/wp-json\/wp\/v2\/posts\/3505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/daveworks.net\/web-design-development-tips\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/daveworks.net\/web-design-development-tips\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/daveworks.net\/web-design-development-tips\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/daveworks.net\/web-design-development-tips\/wp-json\/wp\/v2\/comments?post=3505"}],"version-history":[{"count":5,"href":"https:\/\/daveworks.net\/web-design-development-tips\/wp-json\/wp\/v2\/posts\/3505\/revisions"}],"predecessor-version":[{"id":3510,"href":"https:\/\/daveworks.net\/web-design-development-tips\/wp-json\/wp\/v2\/posts\/3505\/revisions\/3510"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/daveworks.net\/web-design-development-tips\/wp-json\/wp\/v2\/media\/1297"}],"wp:attachment":[{"href":"https:\/\/daveworks.net\/web-design-development-tips\/wp-json\/wp\/v2\/media?parent=3505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/daveworks.net\/web-design-development-tips\/wp-json\/wp\/v2\/categories?post=3505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/daveworks.net\/web-design-development-tips\/wp-json\/wp\/v2\/tags?post=3505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}